{"id":29762,"date":"2025-02-15T18:29:08","date_gmt":"2025-02-15T18:29:08","guid":{"rendered":"https:\/\/repairandshop.ch\/reparation-sur-place\/"},"modified":"2026-01-24T18:26:15","modified_gmt":"2026-01-24T18:26:15","slug":"reparation-sur-place","status":"publish","type":"page","link":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/","title":{"rendered":"R\u00e9paration sur place"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29762\" class=\"elementor elementor-29762 elementor-11502\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-d8b6d77 e-flex e-con-boxed e-con e-parent\" data-id=\"d8b6d77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd5875 elementor-widget elementor-widget-html\" data-id=\"3fd5875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"\r\n  max-width:1000px;\r\n  margin:30px auto;\r\n  padding:20px 25px;\r\n  font-family:Arial, sans-serif;\r\n\">\r\n\r\n  <!-- HEADING -->\r\n  <h1 style=\"\r\n    font-size:32px;\r\n    margin:0 0 10px 0;\r\n    color:#0056FF;\r\n    font-weight:800;\r\n    line-height:1.3;\r\n  \">\r\n    R\u00e9paration sur Place dans Toute la Suisse \u2013 Rapide, S\u00fbre & Professionnelle\r\n  <\/h1>\r\n\r\n  <!-- PARAGRAPH -->\r\n  <p style=\"\r\n    font-size:17px;\r\n    color:#333;\r\n    line-height:1.7;\r\n    margin:12px 0 0 0;\r\n    max-width:850px;\r\n  \">\r\n    Nous proposons des r\u00e9parations professionnelles et fiables dans toute la Suisse.  \r\n    Rendez-vous dans l\u2019une de nos succursales locales et faites diagnostiquer et r\u00e9parer \r\n    votre appareil par nos <strong>techniciens certifi\u00e9s<\/strong> \u2013 souvent en seulement \r\n    <strong>30 \u00e0 60 minutes<\/strong>.  \r\n    Gr\u00e2ce \u00e0 des pi\u00e8ces de rechange premium d\u2019origine, des outils de diagnostic modernes et \r\n    des standards de qualit\u00e9 suisses, nous garantissons un service de r\u00e9paration rapide, s\u00fbr \r\n    et totalement transparent.\r\n  <\/p>\r\n\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-8903c36 e-flex e-con-boxed e-con e-parent\" data-id=\"8903c36\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8688035 elementor-widget elementor-widget-shortcode\" data-id=\"8688035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><style type=\"text\/css\">\n   #asl-storelocator.asl-cont.asl-template-4 .asl-wrapper .asl-top-area  > .pol-lg-12 .Filter_section .search_btn_box .sl-search-btn {margin-bottom: 1.5rem;}\n   body #asl-storelocator.asl-cont.asl-template-4 {--sl-font-size: 18px;--sl-title-size: 15px;--sl-btn-size: 13px;--sl-primary: #004aad;--sl-header: #F7F7F7;--sl-header-color: #32373c;--sl-infobox-color: #555d66;--sl-infobox-bg: #FFFFFF;--sl-infobox-a: #004aad;--sl-action-btn-color: #FFFFFF;--sl-action-btn-bg: #004aad;--sl-color: #555d66;--sl-list-bg: #FFFFFF;--sl-list-title: #32373c;--sl-list-sub-title: #6a6a6a;--sl-highlighted: #F7F7F7;}<\/style>\n<section id=\"asl-storelocator\" class=\"asl-cont asl-template-4 asl-layout-0 asl-bg-0  asl-text-1\">\n        <div class=\"asl-overlay\" id=\"map-loading\">\n        <div class=\"white\"><\/div>\n        <div class=\"sl-loading\">\n          <i class=\"animate-sl-spin icon-spin3\"><\/i>\n          Chargement...        <\/div>\n    <\/div>\n     <div class=\"asl-wrapper\">\n         <div class=\"sl-container\">\n            <div class=\"sl-row asl-top-area\">\n               <div class=\"pol-md-6 pol-lg-6\">\n                  <div class=\"Filter_section\">\n                    <div class=\"search_filter\">\n                       <label for=\"auto-complete-search\" class=\"asl-filter-top-title\">Search Your Nearest Location<\/label>\n                       <div class=\"sl-search-group\">\n                          <input type=\"text\" value=\"\" data-submit=\"disable\" id=\"auto-complete-search\" placeholder=\"Emplacement de recherche\"  class=\"asl-search-address isp_ignore\">\n                          <button aria-label=\"Emplacement de recherche\" title=\"Emplacement de recherche\" type=\"button\" class=\"span-geo\"><i class=\"asl-geo icon-direction-outline\" title=\"Current Location\"><\/i><\/button>\n                       <\/div>\n                    <\/div>\n                    <div class=\"asl-advance-filters hide\">\n                       <div class=\"sl-row\">\n                                                                                                        <div class=\"pol-lg-6 pol-md-12 pol-sm-6 col-12 range_filter hide asl-ddl-filters\">\n                             <div class=\"asl-filter-cntrl rangeFilter\">\n                                <label class=\"asl-cntrl-lbl\">Plage de distances<\/label>\n                                <input id=\"asl-radius-slide\" type=\"text\" class=\"span2\" \/>\n                                <span class=\"rad-unit\">Rayon: <span id=\"asl-radius-input\"><\/span> <span id=\"asl-dist-unit\">Km<\/span><\/span>\n                             <\/div>\n                          <\/div>\n                          <div class=\"pol-lg-6 pol-md-12 pol-sm-6 col-12 Status_filter\">\n                             <div class=\"asl-filter-cntrl\">\n                                <label class=\"asl-cntrl-lbl\">Statut<\/label>\n                                <div class=\"onoffswitch\">\n                                   <input type=\"checkbox\" name=\"onoffswitch\" class=\"onoffswitch-checkbox\" id=\"asl-open-close\" checked>\n                                   <label aria-label=\"Opened Stores\" title=\"Opened Stores\" class=\"onoffswitch-label\" for=\"asl-open-close\">\n                                     <span class=\"onoffswitch-inner\"><\/span>\n                                     <span class=\"onoffswitch-switch\"><\/span>\n                                   <\/label>\n                                <\/div>\n                             <\/div>\n                          <\/div>\n                          \n                       <\/div>\n                    <\/div>\n                    <div class=\"d-md-flex search_btn_box mb-3 mb-md-0\">\n                        <button type=\"button\" title=\"Emplacement de recherche\" class=\"icon-search sl-search-btn\">Recherche<\/button>\n                        <button type=\"button\" title=\"Reset Map\" class=\"ml-0 ml-md-2 asl-reset-btn\">Reset Map<\/button>\n                    <\/div>\n                  <\/div>\n               <\/div>\n               <div class=\"pol-md-6 pol-lg-6\">\n                  <div class=\"asl-map\">\n                    <div class=\"map-image\">\n                       <div id=\"asl-map-canv\" class=\"asl-map-canv\"><\/div>\n                        <div id=\"agile-modal-direction\" class=\"agile-modal fade\">\n    <div class=\"agile-modal-backdrop-in\"><\/div>\n    <div class=\"agile-modal-dialog in\">\n        <div class=\"agile-modal-content\">\n            <div class=\"sl-form-group d-flex justify-content-between\">\n                <h4 >OBTENIR DES DIRECTIONS<\/h4>\n                <button type=\"button\" class=\"close-directions sl-close\" data-dismiss=\"agile-modal\" aria-label=\"Close\">&times;<\/button>\n            <\/div>\n            <div class=\"sl-form-group\">\n                <label for=\"frm-lbl\">Depuis:<\/label>\n                <input type=\"text\" class=\"form-control frm-place\" id=\"frm-lbl\" placeholder=\"Entrez un lieu\">\n            <\/div>\n            <div class=\"sl-form-group\">\n                <label for=\"to-lbl\">Pour:<\/label>\n                <input readonly=\"true\" type=\"text\"  class=\"directions-to form-control\" id=\"to-lbl\" placeholder=\"Adresse de destination pr\u00e9remplie\">\n            <\/div>\n            <div class=\"sl-form-group mb-0\">\n                <label for=\"rbtn-km\" class=\"checkbox-inline\">\n                    <input type=\"radio\" name=\"dist-type\"  id=\"rbtn-km\" value=\"0\"> Km                <\/label>\n                <label for=\"rbtn-mile\" class=\"checkbox-inline\">\n                    <input type=\"radio\" name=\"dist-type\" checked id=\"rbtn-mile\" value=\"1\"> Milles                <\/label>\n            <\/div>\n            <div class=\"sl-form-group mb-0\">\n                <button type=\"submit\" class=\"btn btn-default btn-submit\">OBTENIR DES DIRECTIONS<\/button>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div id=\"asl-geolocation-agile-modal\" class=\"agile-modal fade\">\n  <div class=\"agile-modal-backdrop-in\"><\/div>\n  <div class=\"agile-modal-dialog in\">\n    <div class=\"agile-modal-content\">\n            <div class=\"sl-form-group d-flex justify-content-between\">\n        <h5>Utilisez ma position pour trouver le fournisseur de services le plus proche de chez moi<\/h5>\n        <button type=\"button\" class=\"close-directions sl-close\" data-dismiss=\"agile-modal\" aria-label=\"Close\">&times;<\/button>\n      <\/div>\n      <div class=\"sl-form-group text-center mb-0\">\n        <button type=\"button\" id=\"asl-btn-geolocation\" class=\"btn btn-block btn-default\">UTILISER L&#039;EMPLACEMENT<\/button>\n      <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n<div id=\"asl-desc-agile-modal\" class=\"agile-modal fade\">\n  <div class=\"agile-modal-backdrop-in\"><\/div>\n  <div class=\"agile-modal-dialog in\">\n    <div class=\"agile-modal-content\">\n      <div class=\"sl-row\">\n        <div class=\"pol-md-12\">\n          <div class=\"sl-form-group d-flex justify-content-between\">\n            <h4 class=\"sl-title\">Description<\/h4>\n            <button type=\"button\" class=\"close-directions sl-close\" data-dismiss=\"agile-modal\" aria-label=\"Close\">&times;<\/button>\n          <\/div>\n          <div class=\"sl-desc\"><\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>                    <\/div>\n                  <\/div>\n               <\/div>\n            <\/div>\n            <div class=\"sl-row\">\n               <div class=\"pol-12\">\n                  <div class=\"sl-main-cont\">\n                     <div id=\"asl-panel\" class=\"sl-main-row\">\n                        <div id=\"asl-list\" class=\"asl-panel\">\n                           <div class=\"asl-panel-inner\">\n                                <div class=\"Num_of_store pb-3\">\n                                  <span class=\"count-result-text\">Number Of Shops: <span class=\"count-result\">0<\/span><\/span>\n                                                                      <a class=\"asl-print-btn\" aria-label=\"PRINT\"><span>PRINT<\/span><span class=\"asl-print\"><\/span><\/a>\n                                                                  <\/div>\n                              <div class=\"sl-main-cont-box\">\n                                 <div class=\"sl-list-wrapper\">\n                                    <ul id=\"p-statelist\" class=\"sl-list sl-row panel-inner\">\n                                    <\/ul>\n                                 <\/div>\n                              <\/div>\n                           <\/div>\n                           <div class=\"directions-cont hide\">\n                              <div class=\"agile-modal-header\">\n                                 <button type=\"button\" class=\"close\"><span aria-hidden=\"true\">\u00d7<\/span><\/button>\n                                 <h4>Direction du magasin<\/h4>\n                              <\/div>\n                              <div class=\"rendered-directions\" id=\"asl-rendered-dir\" style=\"direction: ltr;\"><\/div>\n                           <\/div>\n                        <\/div>\n                     <\/div>\n                  <\/div>\n               <\/div>\n            <\/div>\n         <\/div>\n      <\/div>\n<\/section>\n<!-- This plugin is developed by \"Agile Store Locator for WordPress\" https:\/\/agilestorelocator.com --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-6791ad4 e-flex e-con-boxed e-con e-parent\" data-id=\"6791ad4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-859d49d elementor-widget elementor-widget-html\" data-id=\"859d49d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"\r\n  max-width:1000px;\r\n  margin:40px auto;\r\n  padding:25px 30px;\r\n  background:#F5F9FF;\r\n  border-radius:12px;\r\n  border-left:6px solid #0056FF;\r\n  font-family:Arial, sans-serif;\r\n  box-shadow:0 4px 14px rgba(0,0,0,0.06);\r\n\">\r\n\r\n  <h2 style=\"\r\n    margin-top:0;\r\n    font-size:26px;\r\n    font-weight:700;\r\n    color:#0056FF;\r\n  \">\r\n    Pour les clients en dehors de nos emplacements\r\n  <\/h2>\r\n\r\n  <p style=\"\r\n    font-size:16px;\r\n    color:#333;\r\n    line-height:1.7;\r\n    margin-top:12px;\r\n  \">\r\n    Vous n\u2019habitez pas pr\u00e8s de l\u2019une de nos succursales ? Aucun probl\u00e8me !  \r\n    Gr\u00e2ce \u00e0 notre service de r\u00e9paration par envoi postal disponible dans toute la Suisse,  \r\n    vous pouvez envoyer votre appareil facilement depuis chez vous.  \r\n    Nos techniciens effectuent la r\u00e9paration en <strong>24\u201348 heures<\/strong> et renvoient votre appareil \r\n    en toute s\u00e9curit\u00e9 une fois la r\u00e9paration termin\u00e9e.\r\n  <\/p>\r\n\r\n  <ul style=\"\r\n    margin-top:15px;\r\n    padding-left:18px;\r\n    font-size:15px;\r\n    color:#222;\r\n    line-height:1.8;\r\n  \">\r\n    <li>\u2713 Envoyez votre appareil en toute s\u00e9curit\u00e9 par la poste<\/li>\r\n    <li>\u2713 R\u00e9paration rapide en 24\u201348 heures<\/li>\r\n    <li>\u2713 Retour directement \u00e0 votre domicile<\/li>\r\n  <\/ul>\r\n\r\n  <div style=\"margin-top:25px;\">\r\n    <a href=\"https:\/\/repairandshop.ch\/fr\/envoyer-pour-reparation\/\" \r\n       style=\"\r\n         display:inline-block;\r\n         padding:12px 28px;\r\n         background:#0056FF;\r\n         color:white;\r\n         font-size:16px;\r\n         font-weight:600;\r\n         border-radius:8px;\r\n         text-decoration:none;\r\n         box-shadow:0 3px 10px rgba(0,86,255,0.3);\r\n       \">\r\n      D\u00e9marrer la r\u00e9paration par envoi postal\r\n    <\/a>\r\n  <\/div>\r\n\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>R\u00e9paration sur Place dans Toute la Suisse \u2013 Rapide, S\u00fbre &#038; Professionnelle Nous proposons des r\u00e9parations professionnelles et fiables dans<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-29762","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9paration sur place - repairandshop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9paration sur place\" \/>\n<meta property=\"og:description\" content=\"R\u00e9paration sur Place dans Toute la Suisse \u2013 Rapide, S\u00fbre &#038; Professionnelle Nous proposons des r\u00e9parations professionnelles et fiables dans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/\" \/>\n<meta property=\"og:site_name\" content=\"repairandshop\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-24T18:26:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9paration sur place - repairandshop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9paration sur place","og_description":"R\u00e9paration sur Place dans Toute la Suisse \u2013 Rapide, S\u00fbre &#038; Professionnelle Nous proposons des r\u00e9parations professionnelles et fiables dans","og_url":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/","og_site_name":"repairandshop","article_modified_time":"2026-01-24T18:26:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/","url":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/","name":"R\u00e9paration sur place - repairandshop","isPartOf":{"@id":"https:\/\/repairandshop.ch\/fr\/#website"},"datePublished":"2025-02-15T18:29:08+00:00","dateModified":"2026-01-24T18:26:15+00:00","breadcrumb":{"@id":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/repairandshop.ch\/fr\/reparation-sur-place\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/repairandshop.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9paration sur place"}]},{"@type":"WebSite","@id":"https:\/\/repairandshop.ch\/fr\/#website","url":"https:\/\/repairandshop.ch\/fr\/","name":"Repair And Shop","description":"","publisher":{"@id":"https:\/\/repairandshop.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/repairandshop.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/repairandshop.ch\/fr\/#organization","name":"Repair And Shop","url":"https:\/\/repairandshop.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/repairandshop.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/repairandshop.ch\/wp-content\/uploads\/2025\/02\/RepairandShop-Logo.png","contentUrl":"https:\/\/repairandshop.ch\/wp-content\/uploads\/2025\/02\/RepairandShop-Logo.png","width":834,"height":193,"caption":"Repair And Shop"},"image":{"@id":"https:\/\/repairandshop.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/pages\/29762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/comments?post=29762"}],"version-history":[{"count":3,"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/pages\/29762\/revisions"}],"predecessor-version":[{"id":61356,"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/pages\/29762\/revisions\/61356"}],"wp:attachment":[{"href":"https:\/\/repairandshop.ch\/fr\/wp-json\/wp\/v2\/media?parent=29762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}